{"id":2791,"date":"2023-05-19T18:05:31","date_gmt":"2023-05-19T21:05:31","guid":{"rendered":"https:\/\/coffeedinner.com.br\/coffee-dinner-summit-presentara-la-evolucion-de-la-caficultura-en-la-lucha-contra-el-calentamiento-global\/"},"modified":"2023-05-19T18:17:13","modified_gmt":"2023-05-19T21:17:13","slug":"coffee-dinner-summit-presentara-la-evolucion-de-la-caficultura-en-la-lucha-contra-el-calentamiento-global","status":"publish","type":"post","link":"https:\/\/coffeedinner.com.br\/es\/coffee-dinner-summit-presentara-la-evolucion-de-la-caficultura-en-la-lucha-contra-el-calentamiento-global\/","title":{"rendered":"Coffee Dinner &amp; Summit presentar\u00e1 la evoluci\u00f3n de la caficultura en la lucha contra el calentamiento global"},"content":{"rendered":"\n<p><em>Expertos de toda la cadena de producci\u00f3n debatir\u00e1n sobre los avances del sector en buenas pr\u00e1cticas agr\u00edcolas y las posibilidades del mercado del carbono<\/em><\/p>\n\n<p>La descarbonizaci\u00f3n de la producci\u00f3n agr\u00edcola es un factor fundamental para luchar contra el calentamiento global y satisfacer las demandas del mercado de consumo, cada vez m\u00e1s exigente con los productos que respetan y preservan el medio ambiente. El Consejo Brasile\u00f1o de Exportadores de Caf\u00e9 (Cecaf\u00e9) celebrar\u00e1 el \u00abPanel de Sostenibilidad\u00bb el 26 de mayo como parte de la 9\u00aa Cena &amp; Cumbre del Caf\u00e9 en Um Rooftop en S\u00e3o Paulo, Brasil, para ayudar a arrojar luz sobre este debate y presentar el potencial y las oportunidades de la caficultura brasile\u00f1a, as\u00ed como los escenarios actuales y futuros.<\/p>\n\n<p>Patrocinado por el Servicio Brasile\u00f1o de Apoyo a las Micro y Peque\u00f1as Empresas (Sebrae), el evento traer\u00e1 un debate sobre \u00abCaficultura sostenible &#8216;carbono negativo&#8217; frente a los objetivos corporativos globales: Brasil m\u00e1s cerca del mercado de carbono\u00bb, que presentar\u00e1 una visi\u00f3n integrada de representantes de todos los eslabones de la cadena de producci\u00f3n.<\/p>\n\n<p>Entre los subtemas que se debatir\u00e1n figuran \u00abPotencial de la agricultura tropical para la descarbonizaci\u00f3n global\u00bb, \u00abLa caficultura brasile\u00f1a y la mitigaci\u00f3n de los efectos del cambio clim\u00e1tico\u00bb, \u00abDescarbonizaci\u00f3n, oportunidades de valor a\u00f1adido e inversi\u00f3n\u00bb, \u00abHacia la neutralidad de carbono: principales retos para la industria del caf\u00e9\u00bb y \u00abEscenario actual y tendencias del mercado de carbono\u00bb.<\/p>\n\n<p>El panel, que ser\u00e1 moderado por la gerente de Responsabilidad Social y Sostenibilidad de Cecaf\u00e9, Silvia Pizzol, contar\u00e1 con las intervenciones de Eduardo Bastos, CEO de MyCarbon; Alexandre Monteiro, gerente de ESG de Cooxup\u00e9; Fl\u00e1via Paulino da Costa, socia y directora de la Exportadora de Caf\u00e9 Guaxup\u00e9; Mario Cerutti, director de Relaciones Institucionales y Sostenibilidad de la Fundaci\u00f3n Lavazza; y Oscar Schaps, presidente de la divisi\u00f3n latinoamericana de StoneX.<\/p>\n\n<p>Con la experiencia de cada panelista, el Panel de Sostenibilidad de la 9\u00aa Cena &amp; Cumbre del Caf\u00e9 presentar\u00e1 c\u00f3mo la industria brasile\u00f1a del caf\u00e9 ha avanzado y adoptado pr\u00e1cticas sostenibles para mitigar los efectos del cambio clim\u00e1tico y pretende aclarar lo que es necesario para que el sector participe en el mercado de carbono.<\/p>\n\n<p>En vista de las tendencias mundiales y de la se\u00f1alizaci\u00f3n del gran potencial que tiene el mercado de carbono, el Director General de Cecaf\u00e9, Marcos Matos, dice que la entidad est\u00e1 liderando el debate sobre los escenarios actuales y futuros para ayudar a los actores de la cadena productiva a prepararse de la mejor manera posible para que todos, productores, industrias y exportadores puedan obtener los mejores escenarios posibles en este prometedor comercio.<\/p>\n\n<p>\u00abPara explorar esta oportunidad, dentro de un \u00e1rea de trabajo centrada en estrategias de mercado y generaci\u00f3n de ingresos en el campo, Cecaf\u00e9 est\u00e1 estructurando asociaciones con el objetivo de evaluar las metodolog\u00edas existentes y los procesos de registro de proyectos de carbono agrupados para apoyar el desarrollo de una Plataforma de Cr\u00e9ditos de Carbono de Caf\u00e9s de Brasil\u00bb, concluye.<\/p>\n\n<h2 class=\"wp-block-heading\">COFFEE DINNER &amp; SUMMIT<\/h2>\n\n<p>Organizado por Cecaf\u00e9, el evento se destaca como uno de los principales foros mundiales del sector cafetero, reuniendo cada dos a\u00f1os cerca de mil personas y l\u00edderes de todos los segmentos de la caficultura brasile\u00f1a y mundial para promover perspectivas de negocios, crear oportunidades comerciales, compartir experiencias y hacer networking, reuniendo a los actores del agronegocio y a los amantes del L profundo en un ambiente amplio y acogedor.<\/p>\n\n<p>Bajo el tema \u00abCrecimiento de la producci\u00f3n: sus desaf\u00edos y oportunidades en tiempos de ESG\u00bb, la novena edici\u00f3n del Coffee Dinner &amp; Summit pretende promover el debate y la reflexi\u00f3n sobre los desaf\u00edos econ\u00f3micos, clim\u00e1ticos, normativos y log\u00edsticos, y especialmente sobre las iniciativas sostenibles desarrolladas por Brasil y otras naciones cafeteras, que respetan los criterios de gobernanza socioambiental.<\/p>\n\n<h2 class=\"wp-block-heading\">EVENTO CARBONO CERO<\/h2>\n\n<p>En honor a su pilar de acci\u00f3n centrado en la responsabilidad socioambiental, la sostenibilidad y la seguridad alimentaria, Cecaf\u00e9 recibi\u00f3 el Sello Verde de la empresa de reforestaci\u00f3n Ecooar Biodiversity por neutralizar sus emisiones de gases de efecto invernadero (GEI) durante la 9\u00aa Cena y Cumbre del Caf\u00e9.<\/p>\n\n<p>Calculando las emisiones de carbono generadas durante los dos d\u00edas del evento, el Consejo compens\u00f3 m\u00e1s de 2,5 toneladas de CO2 mediante la plantaci\u00f3n de \u00e1rboles aut\u00f3ctonos, contribuyendo a la reforestaci\u00f3n de las \u00c1reas de Preservaci\u00f3n Permanente (APP) de la Hacienda Santa Em\u00edlia, productora de caf\u00e9 en Gar\u00e7a (SP), donde la regeneraci\u00f3n del medio ambiente y la preservaci\u00f3n de las aguas de manantial benefician directa e indirectamente a cerca de un mill\u00f3n de personas de las 62 ciudades de la regi\u00f3n.<\/p>\n\n<h2 class=\"wp-block-heading\">SERVICIO<\/h2>\n\n<p>9\u00ba Coffee Dinner &amp; Summit<br\/>Fecha: 25 y 26 de mayo de 2023<br\/>Lugar: Um Rooftop, S\u00e3o Paulo (SP)<br\/>M\u00e1s informaci\u00f3n: https:\/\/coffeedinner.com.br\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Expertos de toda la cadena de producci\u00f3n debatir\u00e1n sobre los avances del sector en buenas pr\u00e1cticas agr\u00edcolas y las posibilidades del mercado del carbono<\/p>\n","protected":false},"author":1,"featured_media":2783,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-2791","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 14:37:29","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/coffeedinner.com.br\/es\/wp-json\/wp\/v2\/posts\/2791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coffeedinner.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coffeedinner.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coffeedinner.com.br\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/coffeedinner.com.br\/es\/wp-json\/wp\/v2\/comments?post=2791"}],"version-history":[{"count":1,"href":"https:\/\/coffeedinner.com.br\/es\/wp-json\/wp\/v2\/posts\/2791\/revisions"}],"predecessor-version":[{"id":2792,"href":"https:\/\/coffeedinner.com.br\/es\/wp-json\/wp\/v2\/posts\/2791\/revisions\/2792"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coffeedinner.com.br\/es\/wp-json\/wp\/v2\/media\/2783"}],"wp:attachment":[{"href":"https:\/\/coffeedinner.com.br\/es\/wp-json\/wp\/v2\/media?parent=2791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coffeedinner.com.br\/es\/wp-json\/wp\/v2\/categories?post=2791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coffeedinner.com.br\/es\/wp-json\/wp\/v2\/tags?post=2791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}