{"id":856,"date":"2023-03-01T14:30:48","date_gmt":"2023-03-01T17:30:48","guid":{"rendered":"https:\/\/coffeedinner.com.br\/condiciones-para-la-compra-de-entradas-y-el-acceso-a-la-cena-cafe-cumbre-de-los-dias-25-y-26-de-mayo-de-2023\/"},"modified":"2024-12-20T15:19:59","modified_gmt":"2024-12-20T18:19:59","slug":"condiciones-para-la-compra-de-entradas-y-el-acceso-a-la-cena-cafe-cumbre-de-los-dias-25-y-26-de-mayo-de-2023","status":"publish","type":"page","link":"https:\/\/coffeedinner.com.br\/es\/condiciones-para-la-compra-de-entradas-y-el-acceso-a-la-cena-cafe-cumbre-de-los-dias-25-y-26-de-mayo-de-2023\/","title":{"rendered":"T\u00e9rminos y condiciones para la compra de entradas y acceso al Coffee Dinner &amp; Summit, los d\u00edas 2, 3 y 4 de julio de 2025, en el Royal Palm Hall, en Campinas (SP)."},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"856\" class=\"elementor elementor-856 elementor-853\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a00b19f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a00b19f\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<main class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1b2f122\" data-id=\"1b2f122\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-372ef31 font-bold elementor-widget elementor-widget-heading\" data-id=\"372ef31\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">T\u00e9rminos y condiciones para la compra de entradas y acceso al Coffee Dinner &amp; Summit, los d\u00edas 2, 3 y 4 de julio de 2025, en el Royal Palm Hall, en Campinas (SP).<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb8035a elementor-widget elementor-widget-text-editor\" data-id=\"fb8035a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">La compra de una entrada para la Cena Caf\u00e9 &amp; Cumbre implica la aceptaci\u00f3n de los siguientes t\u00e9rminos y condiciones:<\/p>\n<p class=\"p1\"><b>1. Definiciones y conceptos  <\/b><b><\/b><\/p>\n<p class=\"p1\"><b>1.1.  <\/b>Puedes comprar una entrada individual o una mesa con 10 plazas.<\/p>\n<p class=\"p1\"><b>2. Comprar invitaciones individuales o mesas  <\/b><b><\/b><\/p>\n<p class=\"p1\"><b>2.1.  <\/b>La compra de invitaciones individuales o mesas se realiza exclusivamente a trav\u00e9s de la plataforma de pago disponible en www.coffeedinner.com.br, con opciones de pago en efectivo mediante tarjeta de cr\u00e9dito o tal\u00f3n bancario.<\/p>\n<p class=\"p1\"><b>2.2.  <\/b>La compra a trav\u00e9s de www.coffeedinner.com.br genera un ticket de confirmaci\u00f3n para la invitaci\u00f3n individual o la mesa. Este billete no es el permiso de entrada al evento, sino la confirmaci\u00f3n de la compra.<\/p>\n<p class=\"p1\"><b>2.3.  <\/b>El vale de inscripci\u00f3n digital para los d\u00edas 2, 3 y 4 de julio de 2025, por correo electr\u00f3nico, deber\u00e1 presentarse el d\u00eda del evento.<\/p>\n<p class=\"p1\"><b>2.4.  <\/b>El vale digital te dar\u00e1 acceso al programa de tres d\u00edas del evento, los d\u00edas 2, 3 y 4 de julio de 2025.<\/p>\n<p class=\"p1\"><b>2.5.  <\/b>El bono digital es personal y s\u00f3lo ser\u00e1 transferible previa solicitud del titular, con un plazo para cambiar de titularidad de 3 d\u00edas h\u00e1biles antes del inicio del evento, el 2 de julio, con una solicitud expresa a trav\u00e9s del correo electr\u00f3nico de soporte coffeedinner@cecafe.com.br.<\/p>\n<p class=\"p1\"><b>2.6.  <\/b>Los organizadores del Coffee Dinner &amp; Summit no se har\u00e1n responsables de los vales adquiridos a trav\u00e9s de canales no oficiales. El sistema oficial de compra es www.coffeedinner.com.br, a trav\u00e9s de un enlace en el sitio web oficial www.coffeedinner.com.br.<\/p>\n<p class=\"p1\"><b>3. Acreditaci\u00f3n  <\/b><b><\/b><\/p>\n<p class=\"p1\"><b>3.1.  <\/b>El d\u00eda del evento, los participantes deben inscribirse presentando el bono digital recibido por WhatsApp o correo electr\u00f3nico, que puede presentarse por smartphone o en su versi\u00f3n impresa, o simplemente introduciendo su CPF en las m\u00e1quinas expendedoras de entradas de autoservicio.<\/p>\n<p class=\"p1\"><b>3.2.  <\/b>Tras inscribirse, los participantes recibir\u00e1n un distintivo individual con un c\u00f3digo de barras que les dar\u00e1 acceso al recinto.<\/p>\n<p class=\"p1\"><b>3.3.  <\/b>El distintivo s\u00f3lo ser\u00e1 v\u00e1lido para una persona. Los participantes podr\u00e1n entrar y salir del pabell\u00f3n del evento tantas veces como deseen, siempre que se registren a la entrada y a la salida en las puertas de acceso al evento. Despu\u00e9s de registrarse, esta insignia queda bloqueada para nuevas entradas, a menos que se registre la salida.<\/p>\n<p class=\"p1\"><b>3.4.  <\/b>En caso de uso indebido, intento de duplicaci\u00f3n o copia de la credencial, s\u00f3lo tendr\u00e1 acceso al acto el titular de la credencial que haya sido validada en primer lugar, aunque no sea el titular de la misma.<\/p>\n<p class=\"p1\"><b>3.5.  <\/b>El vale digital impreso no se aceptar\u00e1 como forma de acceso al evento, y es imprescindible generar una tarjeta de identificaci\u00f3n en la zona de inscripci\u00f3n.<\/p>\n<p class=\"p1\"><b>3.6.  <\/b>La Cena Caf\u00e9 abrir\u00e1 sus puertas al p\u00fablico para la inscripci\u00f3n a las 18.30 horas del 2 de julio de 2025, con la ceremonia de apertura.<\/p>\n<p class=\"p1\"><b>3.7.  <\/b>La Cumbre del Caf\u00e9 abrir\u00e1 sus puertas al p\u00fablico para la inscripci\u00f3n a las 9.30 horas del 3 de julio.<\/p>\n<p class=\"p1\"><b>4. Seguridad en el lugar de celebraci\u00f3n  <\/b><b><\/b><\/p>\n<p class=\"p1\"><b>4.1.  <\/b>Los participantes en el Coffee Dinner &amp; Summit no podr\u00e1n utilizar objetos que puedan considerarse peligrosos o que no se ajusten a la pol\u00edtica comercial del Coffee Dinner &amp; Summit, como por ejemplo<\/p>\n<p class=\"p1\"><b>4.1.1.<\/b>armas de fuego o armas blancas de cualquier tipo (cuchillos, navajas, etc.);<\/p>\n<p class=\"p1\"><b>4.1.2.<\/b>Objetos punzantes o cortantes (tijeras, estiletes, pinzas, corta\u00fa\u00f1as);<\/p>\n<p class=\"p1\"><b>4.1.3.<\/b>fuegos artificiales, artefactos explosivos, bengalas y artefactos incendiarios de cualquier tipo;<\/p>\n<p class=\"p1\"><b>4.1.4.<\/b>monopat\u00edn, bicicleta o cualquier tipo de veh\u00edculo, motorizado o no, a excepci\u00f3n de los equipos para personas con movilidad reducida;<\/p>\n<p class=\"p1\"><b>4.1.5.<\/b>objetos que pueden utilizarse para el marketing de emboscada;<\/p>\n<p class=\"p1\"><b>4.1.6.<\/b>sustancias venenosas y\/o t\u00f3xicas, incluidas las drogas ilegales;<\/p>\n<p class=\"p1\"><b>4.1.7.<\/b>banderas o carteles que contengan mensajes o s\u00edmbolos con publicidad comercial de no patrocinadores del evento;<\/p>\n<p class=\"p1\"><b>4.1.8.<\/b>drones de cualquier tipo.<\/p>\n<p class=\"p1\"><b>4.1.9.<\/b>alimentos destinados a ser comercializados o que puedan suponer un riesgo para la seguridad.<\/p>\n<p class=\"p1\"><b>4.2.  <\/b>No se admiten animales en los pabellones de la Cena Caf\u00e9 y la Cumbre, salvo perros gu\u00eda debidamente identificados que atiendan a personas con discapacidad visual.<\/p>\n<p class=\"p1\"><b>4.3.  <\/b>Est\u00e1 prohibido fumar en cualquier espacio total o parcialmente cerrado del recinto ferial del Royal Palm Hall, de acuerdo con la Ley Municipal n\u00ba 13.541 de 07\/05\/2009.<\/p>\n<p class=\"p1\"><b>4.4.  <\/b>El Royal Palm Hall sigue el protocolo para eventos corporativos determinado por el Ayuntamiento de Campinas y cumplir\u00e1 las normas vigentes durante el periodo en que se celebre el evento, incluida la posibilidad de exigir el uso de mascarillas, prueba de vacunaci\u00f3n contra el Covid-19 o pruebas r\u00e1pidas.<\/p>\n<p class=\"p1\"><b>5. Derechos de imagen y sonido  <\/b><b><\/b><\/p>\n<p class=\"p1\"><b>5.1.  <\/b>Est\u00e1n estrictamente prohibidas las grabaciones y transmisiones de audio o v\u00eddeo de todas las charlas y paneles de la Cumbre del Caf\u00e9 por cualquier medio, as\u00ed como el uso de c\u00e1maras profesionales (de objetivos intercambiables) o equipos de filmaci\u00f3n profesionales que no hayan sido autorizados previamente por los organizadores del evento.<\/p>\n<p class=\"p1\"><b>5.2.  <\/b>El titular o portador de un distintivo que acceda al Coffee Dinner &amp; Summit declara y acepta que su imagen y audio puedan ser captados durante el evento, cediendo, de forma gratuita y definitiva, todos los derechos de imagen y audio a todos los efectos, incluso consintiendo la cesi\u00f3n a los socios\/proveedores del evento, sin limitaci\u00f3n alguna y sin que pueda caracterizarse ning\u00fan uso indebido de la imagen o cualquier otra vulneraci\u00f3n de derechos y sin ninguna carga y\/o indemnizaci\u00f3n derivada de este uso y\/o cesi\u00f3n.<\/p>\n<p class=\"p1\"><b>6. Pol\u00edtica de cancelaci\u00f3n  <\/b><b><\/b><\/p>\n<p class=\"p1\"><b>6.1.  <\/b>Los organizadores del Coffee Dinner &amp; Summit se reservan el derecho a modificar el programa preestablecido, las fechas y los horarios en cualquier momento, sin previo aviso ni otras condiciones, especialmente por motivos de fuerza mayor o circunstancias imprevisibles.<\/p>\n<p class=\"p1\"><b>6.2.  <\/b>Si el titular del billete desea anular la compra, la solicitud de anulaci\u00f3n debe realizarse en el plazo de 7 (siete) d\u00edas naturales, sin tener en cuenta la fecha de compra, para que se le reembolse el importe, con descuento de los gastos administrativos, de acuerdo con el C\u00f3digo de Defensa del Consumidor. Transcurrido el plazo de 7 (siete) d\u00edas naturales, no se realizar\u00e1n anulaciones de compra y\/o devoluciones de pedidos.<\/p>\n<p class=\"p1\"><b>6.3.  <\/b>El canal para las solicitudes de cancelaci\u00f3n es el soporte oficial del evento por correo electr\u00f3nico o whatsapp.<\/p>\n<p class=\"p1\"><b>6.4.  <\/b>Si la fecha de la Cena Caf\u00e9 &amp; Cumbre se reprograma por cualquier motivo, el billete ser\u00e1 v\u00e1lido autom\u00e1ticamente para la fecha que se fije posteriormente, y no se requerir\u00e1 ninguna otra validaci\u00f3n por parte del titular del billete.<\/p>\n<p class=\"p1\"><b>6.5.  <\/b>Si el titular de la entrada no puede asistir en la nueva fecha, puede solicitar el reembolso en un plazo de 30 (treinta) d\u00edas laborables desde que los organizadores del evento anuncien las directrices de reembolso.<\/p>\n<p class=\"p1\"><b>6.6.  <\/b>En caso de cancelaci\u00f3n del Coffee Dinner &amp; Summit, la organizaci\u00f3n dispondr\u00e1 de hasta 90 (noventa) d\u00edas para tramitar el reembolso y devolver el importe de las entradas una vez cancelado el evento. Transcurrido este plazo, el reembolso se efectuar\u00e1 en el plazo de tres (3) facturas en caso de que la entrada se haya adquirido con tarjeta de cr\u00e9dito (este plazo no est\u00e1 controlado por el Organizador del Coffee Dinner &amp; Summit, ya que se debe a los procedimientos internos de la empresa emisora de la tarjeta de cr\u00e9dito), o en el plazo de 90 (noventa) d\u00edas h\u00e1biles para otras formas de pago.<\/p>\n<p class=\"p1\"><b>6.7.  <\/b>La organizaci\u00f3n no tiene ninguna relaci\u00f3n comercial con la agencia de viajes, que es una mera sugerencia para ayudar a los clientes a contratar servicios de transporte y alojamiento.<\/p>\n<p class=\"p1\"><b>6.8.  <\/b>La organizaci\u00f3n del Coffee Dinner &amp; Summit no se hace responsable de ning\u00fan gasto adicional de alojamiento, viaje, comida, etc. en ninguno de los casos anteriores.<\/p>\n<p class=\"p1\"><b>6.9.  <\/b>No se reembolsar\u00e1n las entradas en caso de retraso o suspensi\u00f3n del Coffee Dinner &amp; Summit, como consecuencia de la ocurrencia de una situaci\u00f3n extraordinaria o imprevisible, ajena a la organizaci\u00f3n, que tenga lugar despu\u00e9s del inicio del evento.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/main>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>T\u00e9rminos y condiciones para la compra de entradas y acceso al Coffee Dinner &amp; Summit, los d\u00edas 2, 3 y 4 de julio de 2025, en el Royal Palm Hall, en Campinas (SP). La compra de una entrada para la Cena Caf\u00e9 &amp; Cumbre implica la aceptaci\u00f3n de los siguientes t\u00e9rminos y condiciones: 1. Definiciones [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-856","page","type-page","status-publish","hentry"],"rankMath":{"parentDomain":"coffeedinner.com.br","noFollowDomains":[],"noFollowExcludeDomains":[],"noFollowExternalLinks":false,"featuredImageNotice":"La imagen destacada debe tener al menos 200 por 200 p\u00edxeles para que Facebook y otros sitios de redes sociales puedan escogerla.","pluginReviewed":true,"postSettings":{"linkSuggestions":true,"useFocusKeyword":false},"frontEndScore":false,"postName":"condiciones-para-la-compra-de-entradas-y-el-acceso-a-la-cena-cafe-cumbre-de-los-dias-25-y-26-de-mayo-de-2023","permalinkFormat":"https:\/\/coffeedinner.com.br\/es\/%pagename%\/","showLockModifiedDate":true,"assessor":{"focusKeywordLink":"https:\/\/coffeedinner.com.br\/wp-admin\/edit.php?focus_keyword=%focus_keyword%&post_type=%post_type%","hasTOCPlugin":true,"primaryTaxonomy":false,"serpData":{"title":"","description":"","focusKeywords":"","pillarContent":false,"canonicalUrl":"","breadcrumbTitle":"","advancedRobots":{"max-snippet":"-1","max-video-preview":"-1","max-image-preview":"large"},"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":"","facebookHasOverlay":false,"facebookImageOverlay":"","facebookAuthor":"","twitterCardType":"","twitterUseFacebook":true,"twitterTitle":"","twitterDescription":"","twitterImage":"","twitterImageID":"","twitterHasOverlay":false,"twitterImageOverlay":"","twitterPlayerUrl":"","twitterPlayerSize":"","twitterPlayerStream":"","twitterPlayerStreamCtype":"","twitterAppDescription":"","twitterAppIphoneName":"","twitterAppIphoneID":"","twitterAppIphoneUrl":"","twitterAppIpadName":"","twitterAppIpadID":"","twitterAppIpadUrl":"","twitterAppGoogleplayName":"","twitterAppGoogleplayID":"","twitterAppGoogleplayUrl":"","twitterAppCountry":"","robots":{"index":true},"twitterAuthor":"nombre de usuario","primaryTerm":0,"authorName":"uon.dev","titleTemplate":"%title% %sep% %sitename%","descriptionTemplate":"%excerpt%","showScoreFrontend":true,"lockModifiedDate":false},"powerWords":["incre\u00edble","asombroso","maravilloso","\u00fanico","hermoso","felicidad","brillante","cautivador","carism\u00e1tico","impactante","claro","completamente","confidencial","confianza","significativo","creativo","definitivamente","delicioso","demostrar","apres\u00farate","decidido","digno","din\u00e1mico","impresionante","esencial","inspirador","innovador","intenso","eficaz","m\u00e1gico","magn\u00edfico","hist\u00f3rico","importante","incre\u00edble","indispensable","inolvidable","irresistible","legendario","luminoso","lujo","m\u00e1gico","magn\u00edfico","majestuoso","memorable","maravilloso","milagroso","motivador","necesario","nuevo","oficial","perfecto","apasionado","persuasivo","fenomenal","placer","popular","poder","prestigioso","prodigioso","profundo","pr\u00f3spero","poderoso","calidad","radiante","r\u00e1pido","exitoso","revolucionario","satisfecho","seguridad","sensacional","sereno","suntuoso","espl\u00e9ndido","sublime","sorprendente","talentoso","terror\u00edfico","\u00fanico","valor","vibrante","victorioso","vivo","verdaderamente","celoso","aut\u00e9ntico","aventurero","espectacular","exclusivo","garantizado","extraordinario","fabuloso","fascinante","formidable","genial","grandioso","gratuito","h\u00e1bil","ilimitado","impecable","infalible","infinitamente","influyente","ingenioso","inolvidable","irremplazable","l\u00edder","maestro","notable","novedoso","pionero","poderoso","reconocido","revolucionario","sorprendente","superior","triunfante","ultra","valiente","valioso","vanguardista","vigoroso","visionario","voluntad","vital","triunfo","glorioso","imparable","inigualable","inteligente","invencible","libertad","orgullo","paz","progreso","renovado","sabidur\u00eda","satisfacci\u00f3n","seguro","serenidad","superaci\u00f3n","talento","transcendente","transformador","valent\u00eda","victoria"],"diacritics":{"A":"[\\u0041\\u24B6\\uFF21\\u00C0\\u00C1\\u00C2\\u1EA6\\u1EA4\\u1EAA\\u1EA8\\u00C3\\u0100\\u0102\\u1EB0\\u1EAE\\u1EB4\\u1EB2\\u0226\\u01E0\\u00C4\\u01DE\\u1EA2\\u00C5\\u01FA\\u01CD\\u0200\\u0202\\u1EA0\\u1EAC\\u1EB6\\u1E00\\u0104\\u023A\\u2C6F]","AA":"[\\uA732]","AE":"[\\u00C6\\u01FC\\u01E2]","AO":"[\\uA734]","AU":"[\\uA736]","AV":"[\\uA738\\uA73A]","AY":"[\\uA73C]","B":"[\\u0042\\u24B7\\uFF22\\u1E02\\u1E04\\u1E06\\u0243\\u0182\\u0181]","C":"[\\u0043\\u24B8\\uFF23\\u0106\\u0108\\u010A\\u010C\\u00C7\\u1E08\\u0187\\u023B\\uA73E]","D":"[\\u0044\\u24B9\\uFF24\\u1E0A\\u010E\\u1E0C\\u1E10\\u1E12\\u1E0E\\u0110\\u018B\\u018A\\u0189\\uA779]","DZ":"[\\u01F1\\u01C4]","Dz":"[\\u01F2\\u01C5]","E":"[\\u0045\\u24BA\\uFF25\\u00C8\\u00C9\\u00CA\\u1EC0\\u1EBE\\u1EC4\\u1EC2\\u1EBC\\u0112\\u1E14\\u1E16\\u0114\\u0116\\u00CB\\u1EBA\\u011A\\u0204\\u0206\\u1EB8\\u1EC6\\u0228\\u1E1C\\u0118\\u1E18\\u1E1A\\u0190\\u018E]","F":"[\\u0046\\u24BB\\uFF26\\u1E1E\\u0191\\uA77B]","G":"[\\u0047\\u24BC\\uFF27\\u01F4\\u011C\\u1E20\\u011E\\u0120\\u01E6\\u0122\\u01E4\\u0193\\uA7A0\\uA77D\\uA77E]","H":"[\\u0048\\u24BD\\uFF28\\u0124\\u1E22\\u1E26\\u021E\\u1E24\\u1E28\\u1E2A\\u0126\\u2C67\\u2C75\\uA78D]","I":"[\\u0049\\u24BE\\uFF29\\u00CC\\u00CD\\u00CE\\u0128\\u012A\\u012C\\u0130\\u00CF\\u1E2E\\u1EC8\\u01CF\\u0208\\u020A\\u1ECA\\u012E\\u1E2C\\u0197]","J":"[\\u004A\\u24BF\\uFF2A\\u0134\\u0248]","K":"[\\u004B\\u24C0\\uFF2B\\u1E30\\u01E8\\u1E32\\u0136\\u1E34\\u0198\\u2C69\\uA740\\uA742\\uA744\\uA7A2]","L":"[\\u004C\\u24C1\\uFF2C\\u013F\\u0139\\u013D\\u1E36\\u1E38\\u013B\\u1E3C\\u1E3A\\u0141\\u023D\\u2C62\\u2C60\\uA748\\uA746\\uA780]","LJ":"[\\u01C7]","Lj":"[\\u01C8]","M":"[\\u004D\\u24C2\\uFF2D\\u1E3E\\u1E40\\u1E42\\u2C6E\\u019C]","N":"[\\u004E\\u24C3\\uFF2E\\u01F8\\u0143\\u00D1\\u1E44\\u0147\\u1E46\\u0145\\u1E4A\\u1E48\\u0220\\u019D\\uA790\\uA7A4]","NJ":"[\\u01CA]","Nj":"[\\u01CB]","O":"[\\u004F\\u24C4\\uFF2F\\u00D2\\u00D3\\u00D4\\u1ED2\\u1ED0\\u1ED6\\u1ED4\\u00D5\\u1E4C\\u022C\\u1E4E\\u014C\\u1E50\\u1E52\\u014E\\u022E\\u0230\\u00D6\\u022A\\u1ECE\\u0150\\u01D1\\u020C\\u020E\\u01A0\\u1EDC\\u1EDA\\u1EE0\\u1EDE\\u1EE2\\u1ECC\\u1ED8\\u01EA\\u01EC\\u00D8\\u01FE\\u0186\\u019F\\uA74A\\uA74C]","OI":"[\\u01A2]","OO":"[\\uA74E]","OU":"[\\u0222]","P":"[\\u0050\\u24C5\\uFF30\\u1E54\\u1E56\\u01A4\\u2C63\\uA750\\uA752\\uA754]","Q":"[\\u0051\\u24C6\\uFF31\\uA756\\uA758\\u024A]","R":"[\\u0052\\u24C7\\uFF32\\u0154\\u1E58\\u0158\\u0210\\u0212\\u1E5A\\u1E5C\\u0156\\u1E5E\\u024C\\u2C64\\uA75A\\uA7A6\\uA782]","S":"[\\u0053\\u24C8\\uFF33\\u1E9E\\u015A\\u1E64\\u015C\\u1E60\\u0160\\u1E66\\u1E62\\u1E68\\u0218\\u015E\\u2C7E\\uA7A8\\uA784]","T":"[\\u0054\\u24C9\\uFF34\\u1E6A\\u0164\\u1E6C\\u021A\\u0162\\u1E70\\u1E6E\\u0166\\u01AC\\u01AE\\u023E\\uA786]","TZ":"[\\uA728]","U":"[\\u0055\\u24CA\\uFF35\\u00D9\\u00DA\\u00DB\\u0168\\u1E78\\u016A\\u1E7A\\u016C\\u00DC\\u01DB\\u01D7\\u01D5\\u01D9\\u1EE6\\u016E\\u0170\\u01D3\\u0214\\u0216\\u01AF\\u1EEA\\u1EE8\\u1EEE\\u1EEC\\u1EF0\\u1EE4\\u1E72\\u0172\\u1E76\\u1E74\\u0244]","V":"[\\u0056\\u24CB\\uFF36\\u1E7C\\u1E7E\\u01B2\\uA75E\\u0245]","VY":"[\\uA760]","W":"[\\u0057\\u24CC\\uFF37\\u1E80\\u1E82\\u0174\\u1E86\\u1E84\\u1E88\\u2C72]","X":"[\\u0058\\u24CD\\uFF38\\u1E8A\\u1E8C]","Y":"[\\u0059\\u24CE\\uFF39\\u1EF2\\u00DD\\u0176\\u1EF8\\u0232\\u1E8E\\u0178\\u1EF6\\u1EF4\\u01B3\\u024E\\u1EFE]","Z":"[\\u005A\\u24CF\\uFF3A\\u0179\\u1E90\\u017B\\u017D\\u1E92\\u1E94\\u01B5\\u0224\\u2C7F\\u2C6B\\uA762]","a":"[\\u0061\\u24D0\\uFF41\\u1E9A\\u00E0\\u00E1\\u00E2\\u1EA7\\u1EA5\\u1EAB\\u1EA9\\u00E3\\u0101\\u0103\\u1EB1\\u1EAF\\u1EB5\\u1EB3\\u0227\\u01E1\\u00E4\\u01DF\\u1EA3\\u00E5\\u01FB\\u01CE\\u0201\\u0203\\u1EA1\\u1EAD\\u1EB7\\u1E01\\u0105\\u2C65\\u0250]","aa":"[\\uA733]","ae":"[\\u00E6\\u01FD\\u01E3]","ao":"[\\uA735]","au":"[\\uA737]","av":"[\\uA739\\uA73B]","ay":"[\\uA73D]","b":"[\\u0062\\u24D1\\uFF42\\u1E03\\u1E05\\u1E07\\u0180\\u0183\\u0253]","c":"[\\u0063\\u24D2\\uFF43\\u0107\\u0109\\u010B\\u010D\\u00E7\\u1E09\\u0188\\u023C\\uA73F\\u2184]","d":"[\\u0064\\u24D3\\uFF44\\u1E0B\\u010F\\u1E0D\\u1E11\\u1E13\\u1E0F\\u0111\\u018C\\u0256\\u0257\\uA77A]","dz":"[\\u01F3\\u01C6]","e":"[\\u0065\\u24D4\\uFF45\\u00E8\\u00E9\\u00EA\\u1EC1\\u1EBF\\u1EC5\\u1EC3\\u1EBD\\u0113\\u1E15\\u1E17\\u0115\\u0117\\u00EB\\u1EBB\\u011B\\u0205\\u0207\\u1EB9\\u1EC7\\u0229\\u1E1D\\u0119\\u1E19\\u1E1B\\u0247\\u025B\\u01DD]","f":"[\\u0066\\u24D5\\uFF46\\u1E1F\\u0192\\uA77C]","g":"[\\u0067\\u24D6\\uFF47\\u01F5\\u011D\\u1E21\\u011F\\u0121\\u01E7\\u0123\\u01E5\\u0260\\uA7A1\\u1D79\\uA77F]","h":"[\\u0068\\u24D7\\uFF48\\u0125\\u1E23\\u1E27\\u021F\\u1E25\\u1E29\\u1E2B\\u1E96\\u0127\\u2C68\\u2C76\\u0265]","hv":"[\\u0195]","i":"[\\u0069\\u24D8\\uFF49\\u00EC\\u00ED\\u00EE\\u0129\\u012B\\u012D\\u00EF\\u1E2F\\u1EC9\\u01D0\\u0209\\u020B\\u1ECB\\u012F\\u1E2D\\u0268\\u0131]","j":"[\\u006A\\u24D9\\uFF4A\\u0135\\u01F0\\u0249]","k":"[\\u006B\\u24DA\\uFF4B\\u1E31\\u01E9\\u1E33\\u0137\\u1E35\\u0199\\u2C6A\\uA741\\uA743\\uA745\\uA7A3]","l":"[\\u006C\\u24DB\\uFF4C\\u0140\\u013A\\u013E\\u1E37\\u1E39\\u013C\\u1E3D\\u1E3B\\u017F\\u0142\\u019A\\u026B\\u2C61\\uA749\\uA781\\uA747]","lj":"[\\u01C9]","m":"[\\u006D\\u24DC\\uFF4D\\u1E3F\\u1E41\\u1E43\\u0271\\u026F]","n":"[\\u006E\\u24DD\\uFF4E\\u01F9\\u0144\\u00F1\\u1E45\\u0148\\u1E47\\u0146\\u1E4B\\u1E49\\u019E\\u0272\\u0149\\uA791\\uA7A5]","nj":"[\\u01CC]","o":"[\\u006F\\u24DE\\uFF4F\\u00F2\\u00F3\\u00F4\\u1ED3\\u1ED1\\u1ED7\\u1ED5\\u00F5\\u1E4D\\u022D\\u1E4F\\u014D\\u1E51\\u1E53\\u014F\\u022F\\u0231\\u00F6\\u022B\\u1ECF\\u0151\\u01D2\\u020D\\u020F\\u01A1\\u1EDD\\u1EDB\\u1EE1\\u1EDF\\u1EE3\\u1ECD\\u1ED9\\u01EB\\u01ED\\u00F8\\u01FF\\u0254\\uA74B\\uA74D\\u0275]","oi":"[\\u01A3]","ou":"[\\u0223]","oo":"[\\uA74F]","p":"[\\u0070\\u24DF\\uFF50\\u1E55\\u1E57\\u01A5\\u1D7D\\uA751\\uA753\\uA755]","q":"[\\u0071\\u24E0\\uFF51\\u024B\\uA757\\uA759]","r":"[\\u0072\\u24E1\\uFF52\\u0155\\u1E59\\u0159\\u0211\\u0213\\u1E5B\\u1E5D\\u0157\\u1E5F\\u024D\\u027D\\uA75B\\uA7A7\\uA783]","s":"[\\u0073\\u24E2\\uFF53\\u015B\\u1E65\\u015D\\u1E61\\u0161\\u1E67\\u1E63\\u1E69\\u0219\\u015F\\u023F\\uA7A9\\uA785\\u1E9B]","ss":"[\\u00DF]","t":"[\\u0074\\u24E3\\uFF54\\u1E6B\\u1E97\\u0165\\u1E6D\\u021B\\u0163\\u1E71\\u1E6F\\u0167\\u01AD\\u0288\\u2C66\\uA787]","tz":"[\\uA729]","u":"[\\u0075\\u24E4\\uFF55\\u00F9\\u00FA\\u00FB\\u0169\\u1E79\\u016B\\u1E7B\\u016D\\u00FC\\u01DC\\u01D8\\u01D6\\u01DA\\u1EE7\\u016F\\u0171\\u01D4\\u0215\\u0217\\u01B0\\u1EEB\\u1EE9\\u1EEF\\u1EED\\u1EF1\\u1EE5\\u1E73\\u0173\\u1E77\\u1E75\\u0289]","v":"[\\u0076\\u24E5\\uFF56\\u1E7D\\u1E7F\\u028B\\uA75F\\u028C]","vy":"[\\uA761]","w":"[\\u0077\\u24E6\\uFF57\\u1E81\\u1E83\\u0175\\u1E87\\u1E85\\u1E98\\u1E89\\u2C73]","x":"[\\u0078\\u24E7\\uFF58\\u1E8B\\u1E8D]","y":"[\\u0079\\u24E8\\uFF59\\u1EF3\\u00FD\\u0177\\u1EF9\\u0233\\u1E8F\\u00FF\\u1EF7\\u1E99\\u1EF5\\u01B4\\u024F\\u1EFF]","z":"[\\u007A\\u24E9\\uFF5A\\u017A\\u1E91\\u017C\\u017E\\u1E93\\u1E95\\u01B6\\u0225\\u0240\\u2C6C\\uA763]"},"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasRedirection":true,"hasBreadcrumb":false},"homeUrl":"https:\/\/coffeedinner.com.br\/es\/","objectID":856,"objectType":"post","locale":"es","localeFull":"es_ES","overlayImages":{"play":{"name":"Icono de reproducci\u00f3n","url":"https:\/\/coffeedinner.com.br\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","path":"\/home\/jrg2zp8a3en1\/public_html\/coffeedinner.com.br\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","position":"middle_center"},"gif":{"name":"Icono GIF","url":"https:\/\/coffeedinner.com.br\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","path":"\/home\/jrg2zp8a3en1\/public_html\/coffeedinner.com.br\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","position":"middle_center"}},"defautOgImage":"https:\/\/coffeedinner.com.br\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/social-placeholder.jpg","customPermalinks":true,"isUserRegistered":false,"autoSuggestKeywords":false,"connectSiteUrl":"https:\/\/rankmath.com\/auth?site=https%3A%2F%2Fcoffeedinner.com.br%2Fes%2F&r=https%3A%2F%2Fcoffeedinner.com.br%2Fes%2Fwp-json%2Fwp%2Fv2%2Fpages%2F856%3Fnonce%3Da4fde3b0f9","maxTags":5,"trendsIcon":"<svg viewBox=\"0 0 610 610\"><path d=\"M18.85,446,174.32,290.48l58.08,58.08L76.93,504a14.54,14.54,0,0,1-20.55,0L18.83,466.48a14.54,14.54,0,0,1,0-20.55Z\" style=\"fill:#4285f4\"\/><path d=\"M242.65,242.66,377.59,377.6l-47.75,47.75a14.54,14.54,0,0,1-20.55,0L174.37,290.43l47.75-47.75A14.52,14.52,0,0,1,242.65,242.66Z\" style=\"fill:#ea4335\"\/><polygon points=\"319.53 319.53 479.26 159.8 537.34 217.88 377.61 377.62 319.53 319.53\" style=\"fill:#fabb05\"\/><path d=\"M594.26,262.73V118.61h0a16.94,16.94,0,0,0-16.94-16.94H433.2a16.94,16.94,0,0,0-12,28.92L565.34,274.71h0a16.94,16.94,0,0,0,28.92-12Z\" style=\"fill:#34a853\"\/><rect width=\"610\" height=\"610\" style=\"fill:none\"\/><\/svg>","showScore":true,"siteFavIcon":"https:\/\/coffeedinner.com.br\/wp-content\/uploads\/2023\/02\/favico.svg","canUser":{"general":false,"advanced":false,"snippet":false,"social":false,"analysis":false,"analytics":false,"content_ai":false},"showKeywordIntent":true,"isPro":false,"is_front_page":false,"trendsUpgradeLink":"https:\/\/rankmath.com\/pricing\/?utm_source=Plugin&utm_medium=CE%20General%20Tab%20Trends&utm_campaign=WP","trendsUpgradeLabel":"Actualizar","trendsPreviewImage":"https:\/\/coffeedinner.com.br\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/trends-preview.jpg","currentEditor":false,"homepageData":{"assessor":{"powerWords":["incre\u00edble","asombroso","maravilloso","\u00fanico","hermoso","felicidad","brillante","cautivador","carism\u00e1tico","impactante","claro","completamente","confidencial","confianza","significativo","creativo","definitivamente","delicioso","demostrar","apres\u00farate","decidido","digno","din\u00e1mico","impresionante","esencial","inspirador","innovador","intenso","eficaz","m\u00e1gico","magn\u00edfico","hist\u00f3rico","importante","incre\u00edble","indispensable","inolvidable","irresistible","legendario","luminoso","lujo","m\u00e1gico","magn\u00edfico","majestuoso","memorable","maravilloso","milagroso","motivador","necesario","nuevo","oficial","perfecto","apasionado","persuasivo","fenomenal","placer","popular","poder","prestigioso","prodigioso","profundo","pr\u00f3spero","poderoso","calidad","radiante","r\u00e1pido","exitoso","revolucionario","satisfecho","seguridad","sensacional","sereno","suntuoso","espl\u00e9ndido","sublime","sorprendente","talentoso","terror\u00edfico","\u00fanico","valor","vibrante","victorioso","vivo","verdaderamente","celoso","aut\u00e9ntico","aventurero","espectacular","exclusivo","garantizado","extraordinario","fabuloso","fascinante","formidable","genial","grandioso","gratuito","h\u00e1bil","ilimitado","impecable","infalible","infinitamente","influyente","ingenioso","inolvidable","irremplazable","l\u00edder","maestro","notable","novedoso","pionero","poderoso","reconocido","revolucionario","sorprendente","superior","triunfante","ultra","valiente","valioso","vanguardista","vigoroso","visionario","voluntad","vital","triunfo","glorioso","imparable","inigualable","inteligente","invencible","libertad","orgullo","paz","progreso","renovado","sabidur\u00eda","satisfacci\u00f3n","seguro","serenidad","superaci\u00f3n","talento","transcendente","transformador","valent\u00eda","victoria"],"diacritics":true,"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasBreadcrumb":false,"serpData":{"title":"%sitename% %page% %sep% %sitedesc%","description":"","titleTemplate":"%sitename% %page% %sep% %sitedesc%","descriptionTemplate":"","focusKeywords":"","breadcrumbTitle":"Home","robots":{"index":true},"advancedRobots":{"max-snippet":"-1","max-video-preview":"-1","max-image-preview":"large"},"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":""}}},"tocTitle":"Table of Contents","tocExcludeHeadings":[],"listStyle":"ul"},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 13:44:44","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"translation_priority"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/coffeedinner.com.br\/es\/wp-json\/wp\/v2\/pages\/856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coffeedinner.com.br\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/coffeedinner.com.br\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/coffeedinner.com.br\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/coffeedinner.com.br\/es\/wp-json\/wp\/v2\/comments?post=856"}],"version-history":[{"count":5,"href":"https:\/\/coffeedinner.com.br\/es\/wp-json\/wp\/v2\/pages\/856\/revisions"}],"predecessor-version":[{"id":4099,"href":"https:\/\/coffeedinner.com.br\/es\/wp-json\/wp\/v2\/pages\/856\/revisions\/4099"}],"wp:attachment":[{"href":"https:\/\/coffeedinner.com.br\/es\/wp-json\/wp\/v2\/media?parent=856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}